{"id":37585,"date":"2024-01-21T13:39:03","date_gmt":"2024-01-21T13:39:03","guid":{"rendered":"https:\/\/www.provenir.com\/spanish\/?p=37585"},"modified":"2026-05-14T09:40:40","modified_gmt":"2026-05-14T09:40:40","slug":"a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo","status":"publish","type":"post","link":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/","title":{"rendered":"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo"},"content":{"rendered":"<h1>A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo<\/h1>\n<div>\n<p><em>El 48 % de los encuestados dice que identificar el fraude es un desaf\u00edo clave, pero solo el 15 % reporta que sus medidas contra el fraude son completamente efectivas.<\/em><\/p>\n<p><strong>Bogot\u00e1, 31 de enero de 2024.<\/strong>&#8211; Provenir, compa\u00f1\u00eda l\u00edder mundial en software de toma de decisiones de riesgo por medio de la Inteligencia Artificial (IA) y Machine Learning (ML) para el sector financiero, ha presentado los resultados de su <a href=\"https:\/\/www.provenir.com\/es\/encuesta-sobre-toma-de-decisiones-de-riesgo-latam-2024\/\">encuesta<\/a> realizada en Latinoam\u00e9rica sobre la toma de decisiones de riesgo en 2024. Provenir encuest\u00f3 a m\u00e1s de 150 l\u00edderes de proveedores de servicios financieros y fintech en la regi\u00f3n para comprender los desaf\u00edos que enfrentan, sus prioridades en la gesti\u00f3n de clientes y su confianza en la precisi\u00f3n y flexibilidad de sus modelos de riesgo<\/p>\n<p>Seg\u00fan Jos\u00e9 Luis Vargas, Vicepresidente Ejecutivo de Provenir para Latinoam\u00e9rica, \u201cla toma de decisiones de riesgo es especialmente crucial a medida que las pol\u00edticas crediticias se vuelven m\u00e1s estrictas, siendo necesario que las instituciones financieras monitoreen de cerca las carteras para comprender y gestionar los riesgos asociados con la concesi\u00f3n de cr\u00e9dito, y as\u00ed mitigar la probabilidad de incumplimiento. Adem\u00e1s, constituye un componente esencial de la inclusi\u00f3n financiera: hacer que los servicios financieros sean accesibles y asequibles para todas las personas y empresas\u201d.<\/p>\n<p>Los resultados indican que el principal desaf\u00edo para el 49 % de los proveedores de servicios financieros es la gesti\u00f3n del riesgo a lo largo del recorrido del cliente, lo que refleja una gran preocupaci\u00f3n por identificar alertas tempranas a lo largo de la relaci\u00f3n usuario-instituci\u00f3n. Adem\u00e1s, la identificaci\u00f3n del fraude (48 %) y la maximizaci\u00f3n de la rentabilidad del cliente (38 %) tambi\u00e9n son desaf\u00edos que resaltan la importancia de tomar decisiones seguras e inteligentes en el entorno financiero actual.<\/p>\n<p>Estos puntos clave, junto con el desarrollo e implementaci\u00f3n de procesos de toma de decisiones de riesgo (35 %), la personalizaci\u00f3n de ofertas a lo largo del ciclo de vida del cliente (34 %), modelos de riesgo inflexibles (29 %) y tecnolog\u00edas obsoletas (20 %), han llevado a los tomadores de decisiones a enfocarse en aspectos que les permitan superar dichos desaf\u00edos, tales como:<\/p>\n<ol>\n<li><strong>La gesti\u00f3n de clientes como prioridad<\/strong>: en los \u00faltimos seis meses, el manejo de clientes existentes (71 %) sigue siendo el enfoque principal en toda Latinoam\u00e9rica, por encima del inter\u00e9s por adquirir nuevos. Espec\u00edficamente, predecir ajustes de cr\u00e9dito (26 %) y revisar estrategias de cobranza y acciones de recuperaci\u00f3n (25 %) fueron las principales prioridades para los encuestados. Este enfoque en la gesti\u00f3n de clientes despu\u00e9s de la adquisici\u00f3n destaca la importancia continua de fortalecer las relaciones con los usuarios en toda Am\u00e9rica Latina.<\/li>\n<li><strong>Modelos a la vanguardia<\/strong>: la gesti\u00f3n del riesgo crediticio es fundamental para ayudar a las instituciones financieras a redefinir los modelos de negocio, ofrecer nuevos productos y servicios, y transformar las interacciones con los clientes. En el informe, m\u00e1s del 50 % de los encuestados expresaron que sus modelos de toma de decisiones sobre riesgo crediticio no son completamente efectivos, a pesar de una mejora del 79 % respecto a 2022. Esto sugiere que a\u00fan existen oportunidades para optimizar la precisi\u00f3n y equidad en las estrategias crediticias.\n<p>\u201cVemos que menos de la mitad de los encuestados conf\u00edan en su capacidad para modificar r\u00e1pidamente la l\u00f3gica de toma de decisiones. Esto plantea desaf\u00edos significativos en un entorno econ\u00f3mico cambiante, lo que destaca la necesidad de mayor flexibilidad y agilidad en los procesos\u201d, agrega Jos\u00e9 Luis Vargas.<\/p>\n<\/li>\n<li>\n<p><strong>Estrategias antifraude y seguridad del cliente<\/strong>: la orquestaci\u00f3n de datos y los procesos de toma de decisiones en riesgo que abarcan la identidad, el cr\u00e9dito y el fraude son imperativos para permitir que las instituciones financieras implementen s\u00f3lidas medidas antifraude; sin embargo, el 48 % de los encuestados citan la identificaci\u00f3n del fraude como un desaf\u00edo clave, pero solo el 15 % de los proveedores de servicios financieros tienen plena confianza en sus medidas antifraude. Esto subraya la importancia de mejorar las estrategias y tecnolog\u00edas destinadas a garantizar la seguridad de la industria y la confianza del cliente, ya que seg\u00fan datos de <a href=\"https:\/\/www.transunion.ph\/content\/dam\/transunion\/ph\/business\/docs\/behaviors-and-attitude-about-household-budgets-spending-and-debts-infographic-retail-report.pdf\">TransUnion<\/a> en Colombia, por ejemplo, el 39 % de los consumidores encuestados reportaron haber sido objetivo de estrategias e intentos de fraude a trav\u00e9s de correo electr\u00f3nico, p\u00e1ginas web, llamadas telef\u00f3nicas o mensajes de texto entre abril y julio de 2023.<\/p>\n<\/li>\n<li><strong>Productos y servicios financieros a la medida<\/strong>: la hiperpersonalizaci\u00f3n de ofertas a las personas enfrenta desaf\u00edos relacionados con la toma de decisiones en tiempo real (30 %), la calidad e integraci\u00f3n de datos (30 %) y el desarrollo e implementaci\u00f3n de an\u00e1lisis avanzados (14 %). Esta puede ser la raz\u00f3n por la que s\u00f3lo el 11 % de las organizaciones encuestadas informan que el aumento de la participaci\u00f3n en la cartera de clientes a trav\u00e9s de t\u00e1cticas de venta cruzada\/especializada es una prioridad. Obst\u00e1culos que subrayan la necesidad de abordar una mejor utilizaci\u00f3n de la tecnolog\u00eda de datos y an\u00e1lisis para ofrecer experiencias m\u00e1s personalizadas.<\/li>\n<\/ol>\n<p>\u201cEn una econom\u00eda desafiante, la gesti\u00f3n y mitigaci\u00f3n proactiva del riesgo se vuelve a\u00fan m\u00e1s cr\u00edtica. Si una organizaci\u00f3n logra hacerlo correctamente, mejorar\u00e1 la retenci\u00f3n de clientes, reducir\u00e1 los incumplimientos, maximizar\u00e1 la inclusi\u00f3n financiera y las oportunidades de ingresos. La toma de decisiones en \u00e1reas como cr\u00e9dito, fraude, cumplimiento y productos es fundamental para el \u00e9xito, el crecimiento y la rentabilidad a largo plazo en el sector de servicios financieros. Las organizaciones pueden obtener una gran ventaja competitiva con la toma de decisiones impulsada por la inteligencia artificial, complementada por la gesti\u00f3n de casos, datos y an\u00e1lisis, para respaldar decisiones m\u00e1s inteligentes y r\u00e1pidas a lo largo del ciclo de vida del cliente\u201d, concluye Jos\u00e9 Luis Vargas.<\/p>\n<p>Los resultados resaltan la vitalidad y complejidad de las decisiones de riesgo en el sector financiero y fintech de Latinoam\u00e9rica. La encuesta se realiz\u00f3 en diciembre de 2023; participaron m\u00e1s de 150 encuestados con sede en Latinoam\u00e9rica, que ocupaban cargos de gerente, director, vicepresidente o superior.<\/p>\n<p>Para ver el informe completo, haz clic en el siguiente <a href=\"https:\/\/provenir.com\/es\/encuesta-sobre-toma-de-decisiones-de-riesgo-latam-2024\/\">enlace.<\/a><\/p>\n<\/div>\n<div>\u00bfTe sientes abrumado\/a por el panorama de plataformas de toma de decisiones sobre riesgos? Consulta nuestra Gu\u00eda del Comprador.<\/div>\n<p><p>\n        <a href=\"\/es\/guia-del-comprador-de-plataformas-de-toma-de-decis\">Obtenga la gu\u00eda<\/a>\n    <\/p>\n<\/p>\n<div>Biblioteca de Recursos<\/div>\n<div>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys cveffect-darken pt-cv-same-height pt-cv-pgloadmore pt-cv-round-btn\" id=\"pt-cv-view-40ead380rw\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"4\" data-cvct=\"3\" data-cvcm=\"1\"><div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37639\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/provenir-anuncia-su-primer-cliente-en-colombia-creci\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-anuncia-su-primer-cliente-en-colombia-creci\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Provenir Anuncia su ...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir anuncia su asociaci\u00f3n con Creci, una fintech colombo-americana que apoya a peque\u00f1as empresas con impacto social en Latinoam\u00e9rica y ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-anuncia-su-primer-cliente-en-colombia-creci\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37638\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/uso-de-datos-no-tradicionales-por-que-es-clave-para-expandir-y-mejorar-la-toma-de-decisiones-de-riesgos-2\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/uso-de-datos-no-tradicionales-por-que-es-clave-para-expandir-y-mejorar-la-toma-de-decisiones-de-riesgos-2\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Uso de datos no trad...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir organiz\u00f3 un panel sobre la creciente relevancia de los datos no tradicionales en Am\u00e9rica Latina. Gast\u00f3n Peralta y l\u00edderes ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/uso-de-datos-no-tradicionales-por-que-es-clave-para-expandir-y-mejorar-la-toma-de-decisiones-de-riesgos-2\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37635\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/mastercard-acelera-la-implementacion-de-soluciones-digital-first\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/mastercard-acelera-la-implementacion-de-soluciones-digital-first\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Mastercard acelera l...<\/a><\/h4>\n<div class=\"pt-cv-content\">Mastercard ampl\u00eda su red de socios en la plataforma Engage, facilitando a fintechs y empresas tecnol\u00f3gicas la implementaci\u00f3n de soluciones ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/mastercard-acelera-la-implementacion-de-soluciones-digital-first\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37633\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/provenir-aliado-inteligente-de-la-inclusion-financiera\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-aliado-inteligente-de-la-inclusion-financiera\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Provenir, aliado int...<\/a><\/h4>\n<div class=\"pt-cv-content\">Gabriela Herrera, l\u00edder de Provenir en Am\u00e9rica Latina, explica c\u00f3mo su plataforma de an\u00e1lisis de riesgo facilita la inclusi\u00f3n financiera, ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-aliado-inteligente-de-la-inclusion-financiera\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37631\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/debate-por-la-privacidad-del-manejo-de-datos-publicos-y-alternativos-big-data-y-machine-learning\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/debate-por-la-privacidad-del-manejo-de-datos-publicos-y-alternativos-big-data-y-machine-learning\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Debate por la privac...<\/a><\/h4>\n<div class=\"pt-cv-content\">En una entrevista con Gaceta Mercantil, Gabriela Herrera, l\u00edder de ventas de Provenir para Am\u00e9rica Latina, explica c\u00f3mo la tecnolog\u00eda ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/debate-por-la-privacidad-del-manejo-de-datos-publicos-y-alternativos-big-data-y-machine-learning\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37627\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/provenir-presenta-data-cloud-marketplace-para-respaldar-la-innovacion-de-productos-y-una-mejor-experiencia-del-cliente\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1046\" src=\"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Provenir_social_post_Data_Cloud__MP_Launch_SP-v2.png\" class=\"pt-cv-thumbnail img-rounded skip-lazy \" alt=\"Provenir presenta Data Cloud + Marketplace para respaldar la innovaci\u00f3n de productos y una mejor experiencia del cliente\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-presenta-data-cloud-marketplace-para-respaldar-la-innovacion-de-productos-y-una-mejor-experiencia-del-cliente\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Provenir presenta Da...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir presenta Data Cloud + Marketplace para respaldar la innovaci\u00f3n de productos y una mejor experiencia del cliente Nuevas soluciones ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-presenta-data-cloud-marketplace-para-respaldar-la-innovacion-de-productos-y-una-mejor-experiencia-del-cliente\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37632\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/transunion-se-une-a-provenir-marketplace-para-ayudar-a-las-empresas-a-acelerar-las-decisiones-de-riesgo-crediticio\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/transunion-se-une-a-provenir-marketplace-para-ayudar-a-las-empresas-a-acelerar-las-decisiones-de-riesgo-crediticio\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">TransUnion se une a ...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir, l\u00edder global en software de an\u00e1lisis de datos y decisiones de riesgo, anuncia la incorporaci\u00f3n de TransUnion al Provenir ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/transunion-se-une-a-provenir-marketplace-para-ayudar-a-las-empresas-a-acelerar-las-decisiones-de-riesgo-crediticio\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37634\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/bigtech-pueden-ser-aliadas-de-la-industria-financiera-segun-provenir\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/bigtech-pueden-ser-aliadas-de-la-industria-financiera-segun-provenir\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Bigtech pueden ser a...<\/a><\/h4>\n<div class=\"pt-cv-content\">Gabriela Herrera, l\u00edder de Provenir en Am\u00e9rica Latina, destaca c\u00f3mo las Bigtechs, con el uso adecuado de tecnolog\u00eda y dentro ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/bigtech-pueden-ser-aliadas-de-la-industria-financiera-segun-provenir\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-24b50aa0cq\">#pt-cv-view-40ead380rw .pt-cv-content-item { padding-top: 20px !important; padding-right: 10px !important; padding-bottom: 0px !important; padding-left: 10px !important; }\n#pt-cv-view-40ead380rw  { margin-right: -10px !important; margin-left: -10px !important; }\n#pt-cv-view-40ead380rw  .pt-cv-ifield   { border-style: none !important; border-radius: 0px 0px 0px 0px !important; }\n#pt-cv-view-40ead380rw .pt-cv-title a, #pt-cv-view-40ead380rw  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-40ead380rw  .pt-cv-title a:hover, #pt-cv-view-40ead380rw  .panel-title:hover   { font-weight: 600 !important; }\n#pt-cv-view-40ead380rw .pt-cv-content , #pt-cv-view-40ead380rw  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-40ead380rw .pt-cv-readmore  { color: #ffffff !important; background-color: #200644 !important; border-width: 1px 1px 1px 1px !important; border-style: solid !important; border-color: rgba(32,6,68,0.85) !important; padding: 10px 20px 10px 20px !important; }\n#pt-cv-view-40ead380rw .pt-cv-readmore:hover  { color: #ffffff !important; background-color: rgba(32,6,68,0.87) !important; }\n#pt-cv-view-40ead380rw  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-40ead380rw  + .pt-cv-pagination-wrapper .pagination .active a, .pt-cv-pagination[data-sid='40ead380rw'] .active a { color: #ffffff !important; background-color: #00aeef !important; }\n.cvp-live-filter[data-sid='40ead380rw'] .cvp-label   { color: #200644 !important; background-color: #00e3d3 !important; padding: 5px 10px !important; margin-bottom: 5px !important; }\n.cvp-live-filter[data-sid='40ead380rw'] input[type='text'], .cvp-live-filter[data-sid='40ead380rw'] div > label, .cvp-live-filter[data-sid='40ead380rw'] select, .cvp-live-filter[data-sid='40ead380rw'] .irs-from, .cvp-live-filter[data-sid='40ead380rw'] .irs-to   { font-size: 16px !important; line-height: 1.3 !important; color: #ffffff !important; background-color: #200644 !important; }\n.cvp-live-submit   { font-size: 14px !important; line-height: 1.3 !important; color: #200644 !important; background-color: #00e3d3 !important; }\n.cvp-live-reset   { font-size: 16px !important; line-height: 1.3 !important; color: #c7d4fc !important; background-color: rgba(160,160,160,0) !important; }\n#pt-cv-view-40ead380rw .img-rounded, #pt-cv-view-40ead380rw .pt-cv-hover-wrapper { -webkit-border-radius: 10px !important; -moz-border-radius: 10px !important; border-radius: 10px !important; }\n#pt-cv-view-40ead380rw .pt-cv-cap-w-img { border-bottom-left-radius: 10px !important; border-bottom-right-radius: 10px !important; }\n#pt-cv-view-40ead380rw .cvp-responsive-image[style*=\"background-image\"] { width: 200px; max-height: 100px; overflow: hidden; aspect-ratio: 2 }\n#pt-cv-view-40ead380rw .cvp-responsive-image img { max-width: 200px; max-height: 100px; aspect-ratio: 2 }<\/style>\r\n\t\t\t<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"animation\":\"slide-bottom-small\",\"header_transparent\":true,\"header_transparent_noplaceholder\":true,\"header_transparent_text_color\":\"light\",\"image_position\":\"bottom-center\",\"image_size\":\"cover\",\"media_background\":\"#120226\",\"padding_bottom\":\"none\",\"padding_top\":\"xlarge\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"class\":\"uk-text-uppercase\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"remove\",\"margin_top\":\"medium\",\"text_align\":\"center\",\"title_color\":\"warning\",\"title_element\":\"div\",\"title_style\":\"h2\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\",\"field\":{\"name\":\"resources\",\"directives\":[{\"name\":\"slice\",\"arguments\":{\"offset\":0}}]}},\"props\":{\"content\":{\"filters\":{\"search\":\"\"},\"name\":\"name\"}}},\"name\":\"Resource head line - AUTO POPULATED\"},{\"type\":\"headline\",\"props\":{\"content\":\"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"medium\",\"margin_top\":\"remove\",\"text_align\":\"center\",\"title_element\":\"h1\",\"title_style\":\"heading-small\"}}]}]}],\"name\":\"hero section\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"2-3,1-3\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"2-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><em>El 48 % de los encuestados dice que identificar el fraude es un desaf\u00edo clave, pero solo el 15 % reporta que sus medidas contra el fraude son completamente efectivas.<\/em><\/p>\n\n\\n\n\n<p><strong>Bogot\u00e1, 31 de enero de 2024.<\/strong>- Provenir, compa\u00f1\u00eda l\u00edder mundial en software de toma de decisiones de riesgo por medio de la Inteligencia Artificial (IA) y Machine Learning (ML) para el sector financiero, ha presentado los resultados de su <a href=\\\"https:\/\/www.provenir.com\/es\/encuesta-sobre-toma-de-decisiones-de-riesgo-latam-2024\/\\\">encuesta<\/a> realizada en Latinoam\u00e9rica sobre la toma de decisiones de riesgo en 2024. Provenir encuest\u00f3 a m\u00e1s de 150 l\u00edderes de proveedores de servicios financieros y fintech en la regi\u00f3n para comprender los desaf\u00edos que enfrentan, sus prioridades en la gesti\u00f3n de clientes y su confianza en la precisi\u00f3n y flexibilidad de sus modelos de riesgo<\/p>\n\n\\n\n\n<p>Seg\u00fan Jos\u00e9 Luis Vargas, Vicepresidente Ejecutivo de Provenir para Latinoam\u00e9rica, \u201cla toma de decisiones de riesgo es especialmente crucial a medida que las pol\u00edticas crediticias se vuelven m\u00e1s estrictas, siendo necesario que las instituciones financieras monitoreen de cerca las carteras para comprender y gestionar los riesgos asociados con la concesi\u00f3n de cr\u00e9dito, y as\u00ed mitigar la probabilidad de incumplimiento. Adem\u00e1s, constituye un componente esencial de la inclusi\u00f3n financiera: hacer que los servicios financieros sean accesibles y asequibles para todas las personas y empresas\u201d.<\/p>\n\n\\n\n\n<p>Los resultados indican que el principal desaf\u00edo para el 49 % de los proveedores de servicios financieros es la gesti\u00f3n del riesgo a lo largo del recorrido del cliente, lo que refleja una gran preocupaci\u00f3n por identificar alertas tempranas a lo largo de la relaci\u00f3n usuario-instituci\u00f3n. Adem\u00e1s, la identificaci\u00f3n del fraude (48 %) y la maximizaci\u00f3n de la rentabilidad del cliente (38 %) tambi\u00e9n son desaf\u00edos que resaltan la importancia de tomar decisiones seguras e inteligentes en el entorno financiero actual.<\/p>\n\n\\n\n\n<p>Estos puntos clave, junto con el desarrollo e implementaci\u00f3n de procesos de toma de decisiones de riesgo (35 %), la personalizaci\u00f3n de ofertas a lo largo del ciclo de vida del cliente (34 %), modelos de riesgo inflexibles (29 %) y tecnolog\u00edas obsoletas (20 %), han llevado a los tomadores de decisiones a enfocarse en aspectos que les permitan superar dichos desaf\u00edos, tales como:<\/p>\n\n\\n\n\n<ol>\\n\n\n<li><strong>La gesti\u00f3n de clientes como prioridad<\/strong>: en los \u00faltimos seis meses, el manejo de clientes existentes (71 %) sigue siendo el enfoque principal en toda Latinoam\u00e9rica, por encima del inter\u00e9s por adquirir nuevos. Espec\u00edficamente, predecir ajustes de cr\u00e9dito (26 %) y revisar estrategias de cobranza y acciones de recuperaci\u00f3n (25 %) fueron las principales prioridades para los encuestados. Este enfoque en la gesti\u00f3n de clientes despu\u00e9s de la adquisici\u00f3n destaca la importancia continua de fortalecer las relaciones con los usuarios en toda Am\u00e9rica Latina.<\/li>\n\n\\n\n\n<li><strong>Modelos a la vanguardia<\/strong>: la gesti\u00f3n del riesgo crediticio es fundamental para ayudar a las instituciones financieras a redefinir los modelos de negocio, ofrecer nuevos productos y servicios, y transformar las interacciones con los clientes. En el informe, m\u00e1s del 50 % de los encuestados expresaron que sus modelos de toma de decisiones sobre riesgo crediticio no son completamente efectivos, a pesar de una mejora del 79 % respecto a 2022. Esto sugiere que a\u00fan existen oportunidades para optimizar la precisi\u00f3n y equidad en las estrategias crediticias.\\n\n\n<p>\u201cVemos que menos de la mitad de los encuestados conf\u00edan en su capacidad para modificar r\u00e1pidamente la l\u00f3gica de toma de decisiones. Esto plantea desaf\u00edos significativos en un entorno econ\u00f3mico cambiante, lo que destaca la necesidad de mayor flexibilidad y agilidad en los procesos\u201d, agrega Jos\u00e9 Luis Vargas.<\/p>\n\n\\n<\/li>\n\n\\n\n\n<li>\\n\n\n<p><strong>Estrategias antifraude y seguridad del cliente<\/strong>: la orquestaci\u00f3n de datos y los procesos de toma de decisiones en riesgo que abarcan la identidad, el cr\u00e9dito y el fraude son imperativos para permitir que las instituciones financieras implementen s\u00f3lidas medidas antifraude; sin embargo, el 48 % de los encuestados citan la identificaci\u00f3n del fraude como un desaf\u00edo clave, pero solo el 15 % de los proveedores de servicios financieros tienen plena confianza en sus medidas antifraude. Esto subraya la importancia de mejorar las estrategias y tecnolog\u00edas destinadas a garantizar la seguridad de la industria y la confianza del cliente, ya que seg\u00fan datos de <a href=\\\"https:\/\/www.transunion.ph\/content\/dam\/transunion\/ph\/business\/docs\/behaviors-and-attitude-about-household-budgets-spending-and-debts-infographic-retail-report.pdf\\\">TransUnion<\/a> en Colombia, por ejemplo, el 39 % de los consumidores encuestados reportaron haber sido objetivo de estrategias e intentos de fraude a trav\u00e9s de correo electr\u00f3nico, p\u00e1ginas web, llamadas telef\u00f3nicas o mensajes de texto entre abril y julio de 2023.<\/p>\n\n\\n<\/li>\n\n\\n\n\n<li><strong>Productos y servicios financieros a la medida<\/strong>: la hiperpersonalizaci\u00f3n de ofertas a las personas enfrenta desaf\u00edos relacionados con la toma de decisiones en tiempo real (30 %), la calidad e integraci\u00f3n de datos (30 %) y el desarrollo e implementaci\u00f3n de an\u00e1lisis avanzados (14 %). Esta puede ser la raz\u00f3n por la que s\u00f3lo el 11 % de las organizaciones encuestadas informan que el aumento de la participaci\u00f3n en la cartera de clientes a trav\u00e9s de t\u00e1cticas de venta cruzada\/especializada es una prioridad. Obst\u00e1culos que subrayan la necesidad de abordar una mejor utilizaci\u00f3n de la tecnolog\u00eda de datos y an\u00e1lisis para ofrecer experiencias m\u00e1s personalizadas.<\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>\u201cEn una econom\u00eda desafiante, la gesti\u00f3n y mitigaci\u00f3n proactiva del riesgo se vuelve a\u00fan m\u00e1s cr\u00edtica. Si una organizaci\u00f3n logra hacerlo correctamente, mejorar\u00e1 la retenci\u00f3n de clientes, reducir\u00e1 los incumplimientos, maximizar\u00e1 la inclusi\u00f3n financiera y las oportunidades de ingresos. La toma de decisiones en \u00e1reas como cr\u00e9dito, fraude, cumplimiento y productos es fundamental para el \u00e9xito, el crecimiento y la rentabilidad a largo plazo en el sector de servicios financieros. Las organizaciones pueden obtener una gran ventaja competitiva con la toma de decisiones impulsada por la inteligencia artificial, complementada por la gesti\u00f3n de casos, datos y an\u00e1lisis, para respaldar decisiones m\u00e1s inteligentes y r\u00e1pidas a lo largo del ciclo de vida del cliente\u201d, concluye Jos\u00e9 Luis Vargas.<\/p>\n\n\\n\n\n<p>Los resultados resaltan la vitalidad y complejidad de las decisiones de riesgo en el sector financiero y fintech de Latinoam\u00e9rica. La encuesta se realiz\u00f3 en diciembre de 2023; participaron m\u00e1s de 150 encuestados con sede en Latinoam\u00e9rica, que ocupaban cargos de gerente, director, vicepresidente o superior.<\/p>\n\n\\n\n\n<p>Para ver el informe completo, haz clic en el siguiente <a href=\\\"https:\/\/provenir.com\/es\/encuesta-sobre-toma-de-decisiones-de-riesgo-latam-2024\/\\\">enlace.<\/a><\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"remove\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"padding\":\"small\",\"position_sticky\":\"row\",\"position_sticky_breakpoint\":\"m\",\"position_sticky_offset\":\"100\",\"style\":\"card-default\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\u00bfTe sientes abrumado\/a por el panorama de plataformas de toma de decisiones sobre riesgos? Consulta nuestra Gu\u00eda del Comprador.\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"text_align\":\"center\",\"title_color\":\"warning\",\"title_element\":\"div\",\"title_style\":\"h3\"}},{\"type\":\"button\",\"props\":{\"button_size\":\"small\",\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Obtenga la gu\u00eda\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"\/es\/guia-del-comprador-de-plataformas-de-toma-de-decis\"}}]}]}]}],\"name\":\"content section\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"class\":\"uk-text-uppercase\",\"content\":\"Biblioteca de Recursos\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_color\":\"background\",\"title_decoration\":\"line\",\"title_element\":\"div\",\"title_style\":\"h4\"}},{\"type\":\"html\",\"props\":{\"content\":\"[pt_view id=\\\"40ead380rw\\\"]\"},\"name\":\"resource library filter\"}]}]}],\"name\":\"ES - Block - filter Resource Library\"}],\"version\":\"5.0.28\",\"yooessentialsVersion\":\"3.0.7\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo El 48 % de los encuestados dice que identificar el fraude es un desaf\u00edo clave, pero solo el 15 % reporta que sus medidas [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"industry":[20],"language":[41],"mktplace-data-type":[],"mktplace-region":[],"mktplace-use-case":[],"resource":[83],"class_list":["post-37585","post","type-post","status-publish","format-standard","hentry","category-noticias","industry-gestion-del-riesgo-crediticio","language-spanish","resource-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El 87 % de las instituciones financieras en Latinoam\u00e9rica carecen de confianza<\/title>\n<meta name=\"description\" content=\"87 % de las instituciones financieras y fintech en Latinoam\u00e9rica no conf\u00edan en poder ajustar r\u00e1pidamente sus decisiones de riesgo ante el aumento de morosidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo\" \/>\n<meta property=\"og:description\" content=\"87 % de las instituciones financieras y fintech en Latinoam\u00e9rica no conf\u00edan en poder ajustar r\u00e1pidamente sus decisiones de riesgo ante el aumento de morosidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Provenir-ES\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-21T13:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T09:40:40+00:00\" \/>\n<meta name=\"author\" content=\"Alejandra Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandra Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/\"},\"author\":{\"name\":\"Alejandra Ramos\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#\\\/schema\\\/person\\\/c2b16f625625df9dc9b8d3977b7f70d9\"},\"headline\":\"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo\",\"datePublished\":\"2024-01-21T13:39:03+00:00\",\"dateModified\":\"2026-05-14T09:40:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/\"},\"wordCount\":1136,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/\",\"name\":\"El 87 % de las instituciones financieras en Latinoam\u00e9rica carecen de confianza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#website\"},\"datePublished\":\"2024-01-21T13:39:03+00:00\",\"dateModified\":\"2026-05-14T09:40:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#\\\/schema\\\/person\\\/c2b16f625625df9dc9b8d3977b7f70d9\"},\"description\":\"87 % de las instituciones financieras y fintech en Latinoam\u00e9rica no conf\u00edan en poder ajustar r\u00e1pidamente sus decisiones de riesgo ante el aumento de morosidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/\",\"name\":\"Provenir-ES\",\"description\":\"Toma de decisiones sobre riesgo crediticio impulsada por IA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#\\\/schema\\\/person\\\/c2b16f625625df9dc9b8d3977b7f70d9\",\"name\":\"Alejandra Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/spanish\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/Ale-96x96.jpg\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/spanish\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/Ale-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.provenir.com\\\/spanish\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/Ale-96x96.jpg\",\"caption\":\"Alejandra Ramos\"},\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/author\\\/alejandra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El 87 % de las instituciones financieras en Latinoam\u00e9rica carecen de confianza","description":"87 % de las instituciones financieras y fintech en Latinoam\u00e9rica no conf\u00edan en poder ajustar r\u00e1pidamente sus decisiones de riesgo ante el aumento de morosidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/","og_locale":"es_ES","og_type":"article","og_title":"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo","og_description":"87 % de las instituciones financieras y fintech en Latinoam\u00e9rica no conf\u00edan en poder ajustar r\u00e1pidamente sus decisiones de riesgo ante el aumento de morosidad.","og_url":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/","og_site_name":"Provenir-ES","article_published_time":"2024-01-21T13:39:03+00:00","article_modified_time":"2026-05-14T09:40:40+00:00","author":"Alejandra Ramos","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alejandra Ramos","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/#article","isPartOf":{"@id":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/"},"author":{"name":"Alejandra Ramos","@id":"https:\/\/www.provenir.com\/es\/#\/schema\/person\/c2b16f625625df9dc9b8d3977b7f70d9"},"headline":"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo","datePublished":"2024-01-21T13:39:03+00:00","dateModified":"2026-05-14T09:40:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/"},"wordCount":1136,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/","url":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/","name":"El 87 % de las instituciones financieras en Latinoam\u00e9rica carecen de confianza","isPartOf":{"@id":"https:\/\/www.provenir.com\/es\/#website"},"datePublished":"2024-01-21T13:39:03+00:00","dateModified":"2026-05-14T09:40:40+00:00","author":{"@id":"https:\/\/www.provenir.com\/es\/#\/schema\/person\/c2b16f625625df9dc9b8d3977b7f70d9"},"description":"87 % de las instituciones financieras y fintech en Latinoam\u00e9rica no conf\u00edan en poder ajustar r\u00e1pidamente sus decisiones de riesgo ante el aumento de morosidad.","breadcrumb":{"@id":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.provenir.com\/es\/a-medida-que-aumentan-las-tasas-de-incumplimiento-el-87-de-las-instituciones-financieras-y-fintech-en-latinoamerica-carecen-de-confianza-en-su-capacidad-para-modificar-rapidamente-decisiones-de-riesgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.provenir.com\/es\/"},{"@type":"ListItem","position":2,"name":"A medida que aumentan las tasas de incumplimiento, el 87 % de las instituciones financieras y fintech en Latinoam\u00e9rica carecen de confianza en su capacidad para modificar r\u00e1pidamente decisiones de riesgo"}]},{"@type":"WebSite","@id":"https:\/\/www.provenir.com\/es\/#website","url":"https:\/\/www.provenir.com\/es\/","name":"Provenir-ES","description":"Toma de decisiones sobre riesgo crediticio impulsada por IA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.provenir.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.provenir.com\/es\/#\/schema\/person\/c2b16f625625df9dc9b8d3977b7f70d9","name":"Alejandra Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.provenir.com\/spanish\/wp-content\/uploads\/sites\/5\/2024\/11\/Ale-96x96.jpg","url":"https:\/\/www.provenir.com\/spanish\/wp-content\/uploads\/sites\/5\/2024\/11\/Ale-96x96.jpg","contentUrl":"https:\/\/www.provenir.com\/spanish\/wp-content\/uploads\/sites\/5\/2024\/11\/Ale-96x96.jpg","caption":"Alejandra Ramos"},"url":"https:\/\/www.provenir.com\/es\/author\/alejandra\/"}]}},"_links":{"self":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/posts\/37585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/comments?post=37585"}],"version-history":[{"count":0,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/posts\/37585\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/media?parent=37585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/categories?post=37585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/tags?post=37585"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/industry?post=37585"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/language?post=37585"},{"taxonomy":"mktplace-data-type","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/mktplace-data-type?post=37585"},{"taxonomy":"mktplace-region","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/mktplace-region?post=37585"},{"taxonomy":"mktplace-use-case","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/mktplace-use-case?post=37585"},{"taxonomy":"resource","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/resource?post=37585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}