{"id":37612,"date":"2022-06-07T11:02:48","date_gmt":"2022-06-07T11:02:48","guid":{"rendered":"https:\/\/www.provenir.com\/spanish\/?p=37612"},"modified":"2026-05-11T16:14:26","modified_gmt":"2026-05-11T16:14:26","slug":"flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz","status":"publish","type":"post","link":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/","title":{"rendered":"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz"},"content":{"rendered":"<h1>Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz<\/h1>\n<div>\n<p><em>La empresa financiera de motos seleccion\u00f3 a Provenir para impulsar su crecimiento y expansi\u00f3n<\/em><\/p>\n<p><strong>MIAMI, FL (MAYO 25, 2022)<\/strong> &#8211; Provenir, l\u00edder mundial en software de toma de decisiones de riesgo impulsado por IA, anunci\u00f3 hoy que Flexiplan, la empresa de financiamiento de motocicletas con sede en El Salvador, ha implementado las soluciones de Provenir para satisfacer todas sus necesidades crediticias, incluida la aprobaci\u00f3n de pr\u00e9stamos en tiempo real, la automatizaci\u00f3n de procesos y la API de f\u00e1cil integraci\u00f3n.<\/p>\n<p>Con procesos de toma de decisiones m\u00e1s eficientes, Flexiplan puede administrar el riesgo de manera m\u00e1s efectiva, d\u00e1ndole la agilidad para responder r\u00e1pidamente a los clientes a trav\u00e9s de su plataforma digital y punto de venta mientras impulsa el crecimiento del negocio. Con insights en tiempo real, entregados por la plataforma Provenir, Flexiplan espera aprobar hasta 60 pr\u00e9stamos en el tiempo que antes hubiera aprobado uno solo.<\/p>\n<p>Flexiplan ayuda a los concesionarios de motocicletas a aumentar las ventas, al mismo tiempo que proporciona clientes valiosos para los socios bancarios. La empresa se basa en la creencia de que el cr\u00e9dito flexible, habilitado por la tecnolog\u00eda moderna, es una herramienta poderosa para promover el comercio y una mejor calidad de vida de los consumidores. Flexiplan necesitaba una plataforma flexible que entregue una gesti\u00f3n de cr\u00e9dito y toma de decisiones de riesgo m\u00e1s \u00e1gil y eficaz para crecer y escalar su negocio, ya que planea expandirse a lo largo de m\u00faltiples pa\u00edses en Am\u00e9rica Central y el Caribe.<\/p>\n<p>Tito Guti\u00e9rrez, director general de Flexiplan enfatiz\u00f3: \u201cProvenir es muy vers\u00e1til ya que nos permite adaptar nuestro comportamiento empresarial a lo que requiere el mercado, y estamos considerando el uso de datos alternativos en el futuro para mejorar a\u00fan m\u00e1s el proceso de aprobaci\u00f3n\u201d.<\/p>\n<p>\u201cHa sido un placer contribuir la trayectoria de digitalizaci\u00f3n de Flexiplan y al crecimiento continuo con las soluciones de toma de decisiones impulsadas por IA de Provenir, que permiten aprobaciones de pr\u00e9stamos en milisegundos\u00bb, dijo Larry Smith, fundador y director general de Provenir. \u201cEl segmento del nicho de motocicletas ha experimentado un crecimiento regional durante los \u00faltimos meses, y Flexiplan est\u00e1 bien posicionado para aprovecharlo. La plataforma flexible de Provenir, que se puede adaptar perfectamente a varios mercados, puede permitir f\u00e1cilmente que Flexiplan ampl\u00ede su negocio\u201d.<\/p>\n<\/div>\n<div>Nuestros recursos de Provenir AI-Powered Risk Decisioning Platform eBooks, videos, art\u00edculos y m\u00e1s para ayudarte a impulsar tu negocio.<\/div>\n<p><p>\n        <a href=\"\/es\/recursos\/\">Recursos<\/a>\n    <\/p>\n<\/p>\n<h3>ADDITIONAL RESOURCES<\/h3>\n<div>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys cveffect-darken pt-cv-same-height pt-cv-pgloadmore pt-cv-round-btn\" id=\"pt-cv-view-40ead380rw\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"4\" data-cvct=\"3\" data-cvcm=\"1\"><div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37639\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/provenir-anuncia-su-primer-cliente-en-colombia-creci\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-anuncia-su-primer-cliente-en-colombia-creci\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Provenir Anuncia su ...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir anuncia su asociaci\u00f3n con Creci, una fintech colombo-americana que apoya a peque\u00f1as empresas con impacto social en Latinoam\u00e9rica y ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-anuncia-su-primer-cliente-en-colombia-creci\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37638\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/uso-de-datos-no-tradicionales-por-que-es-clave-para-expandir-y-mejorar-la-toma-de-decisiones-de-riesgos-2\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/uso-de-datos-no-tradicionales-por-que-es-clave-para-expandir-y-mejorar-la-toma-de-decisiones-de-riesgos-2\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Uso de datos no trad...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir organiz\u00f3 un panel sobre la creciente relevancia de los datos no tradicionales en Am\u00e9rica Latina. Gast\u00f3n Peralta y l\u00edderes ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/uso-de-datos-no-tradicionales-por-que-es-clave-para-expandir-y-mejorar-la-toma-de-decisiones-de-riesgos-2\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37635\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/mastercard-acelera-la-implementacion-de-soluciones-digital-first\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/mastercard-acelera-la-implementacion-de-soluciones-digital-first\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Mastercard acelera l...<\/a><\/h4>\n<div class=\"pt-cv-content\">Mastercard ampl\u00eda su red de socios en la plataforma Engage, facilitando a fintechs y empresas tecnol\u00f3gicas la implementaci\u00f3n de soluciones ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/mastercard-acelera-la-implementacion-de-soluciones-digital-first\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37633\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/provenir-aliado-inteligente-de-la-inclusion-financiera\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-aliado-inteligente-de-la-inclusion-financiera\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Provenir, aliado int...<\/a><\/h4>\n<div class=\"pt-cv-content\">Gabriela Herrera, l\u00edder de Provenir en Am\u00e9rica Latina, explica c\u00f3mo su plataforma de an\u00e1lisis de riesgo facilita la inclusi\u00f3n financiera, ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-aliado-inteligente-de-la-inclusion-financiera\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37631\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/debate-por-la-privacidad-del-manejo-de-datos-publicos-y-alternativos-big-data-y-machine-learning\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/debate-por-la-privacidad-del-manejo-de-datos-publicos-y-alternativos-big-data-y-machine-learning\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Debate por la privac...<\/a><\/h4>\n<div class=\"pt-cv-content\">En una entrevista con Gaceta Mercantil, Gabriela Herrera, l\u00edder de ventas de Provenir para Am\u00e9rica Latina, explica c\u00f3mo la tecnolog\u00eda ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/debate-por-la-privacidad-del-manejo-de-datos-publicos-y-alternativos-big-data-y-machine-learning\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37627\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/provenir-presenta-data-cloud-marketplace-para-respaldar-la-innovacion-de-productos-y-una-mejor-experiencia-del-cliente\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1046\" src=\"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Provenir_social_post_Data_Cloud__MP_Launch_SP-v2.png\" class=\"pt-cv-thumbnail img-rounded skip-lazy \" alt=\"Provenir presenta Data Cloud + Marketplace para respaldar la innovaci\u00f3n de productos y una mejor experiencia del cliente\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-presenta-data-cloud-marketplace-para-respaldar-la-innovacion-de-productos-y-una-mejor-experiencia-del-cliente\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Provenir presenta Da...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir presenta Data Cloud + Marketplace para respaldar la innovaci\u00f3n de productos y una mejor experiencia del cliente Nuevas soluciones ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/provenir-presenta-data-cloud-marketplace-para-respaldar-la-innovacion-de-productos-y-una-mejor-experiencia-del-cliente\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37632\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/transunion-se-une-a-provenir-marketplace-para-ayudar-a-las-empresas-a-acelerar-las-decisiones-de-riesgo-crediticio\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/transunion-se-une-a-provenir-marketplace-para-ayudar-a-las-empresas-a-acelerar-las-decisiones-de-riesgo-crediticio\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">TransUnion se une a ...<\/a><\/h4>\n<div class=\"pt-cv-content\">Provenir, l\u00edder global en software de an\u00e1lisis de datos y decisiones de riesgo, anuncia la incorporaci\u00f3n de TransUnion al Provenir ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/transunion-se-une-a-provenir-marketplace-para-ayudar-a-las-empresas-a-acelerar-las-decisiones-de-riesgo-crediticio\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div>\n<div class=\"col-md-3 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"37634\"><div class='pt-cv-ifield'><a href=\"https:\/\/www.provenir.com\/es\/bigtech-pueden-ser-aliadas-de-la-industria-financiera-segun-provenir\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default pt-cv-thumb-wrapper cvplbd cvp-responsive-image img-rounded\" target=\"_self\" data-iw=\"200\" data-ih=\"100\"><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.provenir.com\/es\/bigtech-pueden-ser-aliadas-de-la-industria-financiera-segun-provenir\/\" class=\"_self cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Bigtech pueden ser a...<\/a><\/h4>\n<div class=\"pt-cv-content\">Gabriela Herrera, l\u00edder de Provenir en Am\u00e9rica Latina, destaca c\u00f3mo las Bigtechs, con el uso adecuado de tecnolog\u00eda y dentro ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.provenir.com\/es\/bigtech-pueden-ser-aliadas-de-la-industria-financiera-segun-provenir\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\" data-iw=\"200\" data-ih=\"100\">Leer m\u00e1s<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-15cfad54oj\">#pt-cv-view-40ead380rw .pt-cv-content-item { padding-top: 20px !important; padding-right: 10px !important; padding-bottom: 0px !important; padding-left: 10px !important; }\n#pt-cv-view-40ead380rw  { margin-right: -10px !important; margin-left: -10px !important; }\n#pt-cv-view-40ead380rw  .pt-cv-ifield   { border-style: none !important; border-radius: 0px 0px 0px 0px !important; }\n#pt-cv-view-40ead380rw .pt-cv-title a, #pt-cv-view-40ead380rw  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-40ead380rw  .pt-cv-title a:hover, #pt-cv-view-40ead380rw  .panel-title:hover   { font-weight: 600 !important; }\n#pt-cv-view-40ead380rw .pt-cv-content , #pt-cv-view-40ead380rw  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-40ead380rw .pt-cv-readmore  { color: #ffffff !important; background-color: #200644 !important; border-width: 1px 1px 1px 1px !important; border-style: solid !important; border-color: rgba(32,6,68,0.85) !important; padding: 10px 20px 10px 20px !important; }\n#pt-cv-view-40ead380rw .pt-cv-readmore:hover  { color: #ffffff !important; background-color: rgba(32,6,68,0.87) !important; }\n#pt-cv-view-40ead380rw  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-40ead380rw  + .pt-cv-pagination-wrapper .pagination .active a, .pt-cv-pagination[data-sid='40ead380rw'] .active a { color: #ffffff !important; background-color: #00aeef !important; }\n.cvp-live-filter[data-sid='40ead380rw'] .cvp-label   { color: #200644 !important; background-color: #00e3d3 !important; padding: 5px 10px !important; margin-bottom: 5px !important; }\n.cvp-live-filter[data-sid='40ead380rw'] input[type='text'], .cvp-live-filter[data-sid='40ead380rw'] div > label, .cvp-live-filter[data-sid='40ead380rw'] select, .cvp-live-filter[data-sid='40ead380rw'] .irs-from, .cvp-live-filter[data-sid='40ead380rw'] .irs-to   { font-size: 16px !important; line-height: 1.3 !important; color: #ffffff !important; background-color: #200644 !important; }\n.cvp-live-submit   { font-size: 14px !important; line-height: 1.3 !important; color: #200644 !important; background-color: #00e3d3 !important; }\n.cvp-live-reset   { font-size: 16px !important; line-height: 1.3 !important; color: #c7d4fc !important; background-color: rgba(160,160,160,0) !important; }\n#pt-cv-view-40ead380rw .img-rounded, #pt-cv-view-40ead380rw .pt-cv-hover-wrapper { -webkit-border-radius: 10px !important; -moz-border-radius: 10px !important; border-radius: 10px !important; }\n#pt-cv-view-40ead380rw .pt-cv-cap-w-img { border-bottom-left-radius: 10px !important; border-bottom-right-radius: 10px !important; }\n#pt-cv-view-40ead380rw .cvp-responsive-image[style*=\"background-image\"] { width: 200px; max-height: 100px; overflow: hidden; aspect-ratio: 2 }\n#pt-cv-view-40ead380rw .cvp-responsive-image img { max-width: 200px; max-height: 100px; aspect-ratio: 2 }<\/style>\r\n\t\t\t<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"animation\":\"slide-bottom-small\",\"header_transparent\":true,\"header_transparent_noplaceholder\":true,\"header_transparent_text_color\":\"light\",\"image_position\":\"bottom-center\",\"image_size\":\"cover\",\"media_background\":\"#120226\",\"padding_bottom\":\"none\",\"padding_top\":\"xlarge\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"class\":\"uk-text-uppercase\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"remove\",\"margin_top\":\"medium\",\"text_align\":\"center\",\"title_color\":\"warning\",\"title_element\":\"h6\",\"title_style\":\"h2\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\",\"field\":{\"name\":\"resources\",\"directives\":[{\"name\":\"slice\",\"arguments\":{\"offset\":0}}]}},\"props\":{\"content\":{\"filters\":{\"search\":\"\"},\"name\":\"name\"}}},\"name\":\"Resource head line - AUTO POPULATED\"},{\"type\":\"headline\",\"props\":{\"content\":\"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"medium\",\"margin_top\":\"remove\",\"text_align\":\"center\",\"title_element\":\"h1\",\"title_style\":\"heading-small\"}}]}]}],\"name\":\"hero section\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"2-3,1-3\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"2-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><em>La empresa financiera de motos seleccion\u00f3 a Provenir para impulsar su crecimiento y expansi\u00f3n<\/em><\/p>\n\n\\n\n\n<p><strong>MIAMI, FL (MAYO 25, 2022)<\/strong> - Provenir, l\u00edder mundial en software de toma de decisiones de riesgo impulsado por IA, anunci\u00f3 hoy que Flexiplan, la empresa de financiamiento de motocicletas con sede en El Salvador, ha implementado las soluciones de Provenir para satisfacer todas sus necesidades crediticias, incluida la aprobaci\u00f3n de pr\u00e9stamos en tiempo real, la automatizaci\u00f3n de procesos y la API de f\u00e1cil integraci\u00f3n.<\/p>\n\n\\n\n\n<p>Con procesos de toma de decisiones m\u00e1s eficientes, Flexiplan puede administrar el riesgo de manera m\u00e1s efectiva, d\u00e1ndole la agilidad para responder r\u00e1pidamente a los clientes a trav\u00e9s de su plataforma digital y punto de venta mientras impulsa el crecimiento del negocio. Con insights en tiempo real, entregados por la plataforma Provenir, Flexiplan espera aprobar hasta 60 pr\u00e9stamos en el tiempo que antes hubiera aprobado uno solo.<\/p>\n\n\\n\n\n<p>Flexiplan ayuda a los concesionarios de motocicletas a aumentar las ventas, al mismo tiempo que proporciona clientes valiosos para los socios bancarios. La empresa se basa en la creencia de que el cr\u00e9dito flexible, habilitado por la tecnolog\u00eda moderna, es una herramienta poderosa para promover el comercio y una mejor calidad de vida de los consumidores. Flexiplan necesitaba una plataforma flexible que entregue una gesti\u00f3n de cr\u00e9dito y toma de decisiones de riesgo m\u00e1s \u00e1gil y eficaz para crecer y escalar su negocio, ya que planea expandirse a lo largo de m\u00faltiples pa\u00edses en Am\u00e9rica Central y el Caribe.<\/p>\n\n\\n\n\n<p>Tito Guti\u00e9rrez, director general de Flexiplan enfatiz\u00f3: \u201cProvenir es muy vers\u00e1til ya que nos permite adaptar nuestro comportamiento empresarial a lo que requiere el mercado, y estamos considerando el uso de datos alternativos en el futuro para mejorar a\u00fan m\u00e1s el proceso de aprobaci\u00f3n\u201d.<\/p>\n\n\\n\n\n<p>\u201cHa sido un placer contribuir la trayectoria de digitalizaci\u00f3n de Flexiplan y al crecimiento continuo con las soluciones de toma de decisiones impulsadas por IA de Provenir, que permiten aprobaciones de pr\u00e9stamos en milisegundos'', dijo Larry Smith, fundador y director general de Provenir. \u201cEl segmento del nicho de motocicletas ha experimentado un crecimiento regional durante los \u00faltimos meses, y Flexiplan est\u00e1 bien posicionado para aprovecharlo. La plataforma flexible de Provenir, que se puede adaptar perfectamente a varios mercados, puede permitir f\u00e1cilmente que Flexiplan ampl\u00ede su negocio\u201d.<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"remove\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"padding\":\"small\",\"position_sticky\":\"row\",\"position_sticky_breakpoint\":\"m\",\"position_sticky_offset\":\"100\",\"style\":\"card-default\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Nuestros recursos de Provenir AI-Powered Risk Decisioning Platform eBooks, videos, art\u00edculos y m\u00e1s para ayudarte a impulsar tu negocio.\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"text_align\":\"center\",\"title_color\":\"warning\",\"title_element\":\"div\",\"title_style\":\"h3\"}},{\"type\":\"button\",\"props\":{\"button_size\":\"small\",\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Recursos\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"\/es\/recursos\/\"}}]}]}]}],\"name\":\"content section\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"ADDITIONAL RESOURCES\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_color\":\"background\",\"title_decoration\":\"line\",\"title_element\":\"h3\",\"title_style\":\"text-large\"},\"name\":\"RESOURCE LIBRARY\"},{\"type\":\"html\",\"props\":{\"content\":\"[pt_view id=\\\"40ead380rw\\\"]\"},\"name\":\"resource library filter\"}]}]}],\"name\":\"Block - Resource Libraries\"}],\"version\":\"5.0.28\",\"yooessentialsVersion\":\"3.0.7\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Provenir, l\u00edder mundial en software de toma de decisiones de riesgo impulsado por IA, anunci\u00f3 que Flexiplan, empresa de financiamiento de motocicletas en El Salvador, ha implementado las soluciones de Provenir para aprobar pr\u00e9stamos en tiempo real, automatizar procesos e integrar su API f\u00e1cilmente. Flexiplan busca aprobar hasta 60 pr\u00e9stamos en el tiempo que antes tomaba aprobar uno, mejorando la agilidad del negocio y apoyando su expansi\u00f3n en Am\u00e9rica Central y el Caribe.<\/p>\n","protected":false},"author":14,"featured_media":37613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"industry":[34],"language":[41],"mktplace-data-type":[],"mktplace-region":[],"mktplace-use-case":[],"resource":[83],"class_list":["post-37612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","industry-provenir","language-spanish","resource-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FlexiPlan agiliza aprobaciones y mejora la gesti\u00f3n de riesgo con Provenir<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo FlexiPlan redujo el tiempo de aprobaci\u00f3n de cr\u00e9dito mientras mejoraba la gesti\u00f3n de riesgo con Provenir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo FlexiPlan redujo el tiempo de aprobaci\u00f3n de cr\u00e9dito mientras mejoraba la gesti\u00f3n de riesgo con Provenir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/\" \/>\n<meta property=\"og:site_name\" content=\"Provenir-ES\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-07T11:02:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T16:14:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Flexiplan_press_release_social_SP-768x401-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandra Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandra Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/\"},\"author\":{\"name\":\"Alejandra Ramos\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#\\\/schema\\\/person\\\/c2b16f625625df9dc9b8d3977b7f70d9\"},\"headline\":\"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz\",\"datePublished\":\"2022-06-07T11:02:48+00:00\",\"dateModified\":\"2026-05-11T16:14:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/\"},\"wordCount\":473,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/08\\\/Flexiplan_press_release_social_SP-768x401-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/\",\"name\":\"FlexiPlan agiliza aprobaciones y mejora la gesti\u00f3n de riesgo con Provenir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/08\\\/Flexiplan_press_release_social_SP-768x401-1.jpg\",\"datePublished\":\"2022-06-07T11:02:48+00:00\",\"dateModified\":\"2026-05-11T16:14:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#\\\/schema\\\/person\\\/c2b16f625625df9dc9b8d3977b7f70d9\"},\"description\":\"Descubre c\u00f3mo FlexiPlan redujo el tiempo de aprobaci\u00f3n de cr\u00e9dito mientras mejoraba la gesti\u00f3n de riesgo con Provenir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/08\\\/Flexiplan_press_release_social_SP-768x401-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/08\\\/Flexiplan_press_release_social_SP-768x401-1.jpg\",\"width\":768,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/\",\"name\":\"Provenir-ES\",\"description\":\"Toma de decisiones sobre riesgo crediticio impulsada por IA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/#\\\/schema\\\/person\\\/c2b16f625625df9dc9b8d3977b7f70d9\",\"name\":\"Alejandra Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.provenir.com\\\/spanish\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/Ale-96x96.jpg\",\"url\":\"https:\\\/\\\/www.provenir.com\\\/spanish\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/Ale-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.provenir.com\\\/spanish\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/Ale-96x96.jpg\",\"caption\":\"Alejandra Ramos\"},\"url\":\"https:\\\/\\\/www.provenir.com\\\/es\\\/author\\\/alejandra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FlexiPlan agiliza aprobaciones y mejora la gesti\u00f3n de riesgo con Provenir","description":"Descubre c\u00f3mo FlexiPlan redujo el tiempo de aprobaci\u00f3n de cr\u00e9dito mientras mejoraba la gesti\u00f3n de riesgo con Provenir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/","og_locale":"es_ES","og_type":"article","og_title":"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz","og_description":"Descubre c\u00f3mo FlexiPlan redujo el tiempo de aprobaci\u00f3n de cr\u00e9dito mientras mejoraba la gesti\u00f3n de riesgo con Provenir.","og_url":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/","og_site_name":"Provenir-ES","article_published_time":"2022-06-07T11:02:48+00:00","article_modified_time":"2026-05-11T16:14:26+00:00","og_image":[{"width":768,"height":401,"url":"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Flexiplan_press_release_social_SP-768x401-1.jpg","type":"image\/jpeg"}],"author":"Alejandra Ramos","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alejandra Ramos","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#article","isPartOf":{"@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/"},"author":{"name":"Alejandra Ramos","@id":"https:\/\/www.provenir.com\/es\/#\/schema\/person\/c2b16f625625df9dc9b8d3977b7f70d9"},"headline":"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz","datePublished":"2022-06-07T11:02:48+00:00","dateModified":"2026-05-11T16:14:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/"},"wordCount":473,"commentCount":0,"image":{"@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Flexiplan_press_release_social_SP-768x401-1.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/","url":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/","name":"FlexiPlan agiliza aprobaciones y mejora la gesti\u00f3n de riesgo con Provenir","isPartOf":{"@id":"https:\/\/www.provenir.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#primaryimage"},"image":{"@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Flexiplan_press_release_social_SP-768x401-1.jpg","datePublished":"2022-06-07T11:02:48+00:00","dateModified":"2026-05-11T16:14:26+00:00","author":{"@id":"https:\/\/www.provenir.com\/es\/#\/schema\/person\/c2b16f625625df9dc9b8d3977b7f70d9"},"description":"Descubre c\u00f3mo FlexiPlan redujo el tiempo de aprobaci\u00f3n de cr\u00e9dito mientras mejoraba la gesti\u00f3n de riesgo con Provenir.","breadcrumb":{"@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#primaryimage","url":"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Flexiplan_press_release_social_SP-768x401-1.jpg","contentUrl":"https:\/\/www.provenir.com\/es\/wp-content\/uploads\/sites\/5\/2024\/08\/Flexiplan_press_release_social_SP-768x401-1.jpg","width":768,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/www.provenir.com\/es\/flexiplan-recorto-el-tiempo-de-aprobacion-de-credito-a-la-vez-gestionando-el-riesgo-de-forma-mas-eficaz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.provenir.com\/es\/"},{"@type":"ListItem","position":2,"name":"Flexiplan Recort\u00f3 el Tiempo de Aprobaci\u00f3n de Cr\u00e9dito a la Vez Gestionando el Riesgo de Forma m\u00e1s Eficaz"}]},{"@type":"WebSite","@id":"https:\/\/www.provenir.com\/es\/#website","url":"https:\/\/www.provenir.com\/es\/","name":"Provenir-ES","description":"Toma de decisiones sobre riesgo crediticio impulsada por IA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.provenir.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.provenir.com\/es\/#\/schema\/person\/c2b16f625625df9dc9b8d3977b7f70d9","name":"Alejandra Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.provenir.com\/spanish\/wp-content\/uploads\/sites\/5\/2024\/11\/Ale-96x96.jpg","url":"https:\/\/www.provenir.com\/spanish\/wp-content\/uploads\/sites\/5\/2024\/11\/Ale-96x96.jpg","contentUrl":"https:\/\/www.provenir.com\/spanish\/wp-content\/uploads\/sites\/5\/2024\/11\/Ale-96x96.jpg","caption":"Alejandra Ramos"},"url":"https:\/\/www.provenir.com\/es\/author\/alejandra\/"}]}},"_links":{"self":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/posts\/37612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/comments?post=37612"}],"version-history":[{"count":0,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/posts\/37612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/media\/37613"}],"wp:attachment":[{"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/media?parent=37612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/categories?post=37612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/tags?post=37612"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/industry?post=37612"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/language?post=37612"},{"taxonomy":"mktplace-data-type","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/mktplace-data-type?post=37612"},{"taxonomy":"mktplace-region","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/mktplace-region?post=37612"},{"taxonomy":"mktplace-use-case","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/mktplace-use-case?post=37612"},{"taxonomy":"resource","embeddable":true,"href":"https:\/\/www.provenir.com\/es\/wp-json\/wp\/v2\/resource?post=37612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}